{"id":493,"date":"2023-08-15T18:55:44","date_gmt":"2023-08-15T17:55:44","guid":{"rendered":"https:\/\/calmaylagom.eu\/?p=493"},"modified":"2023-08-15T18:55:46","modified_gmt":"2023-08-15T17:55:46","slug":"visita-a-becerril-de-campos","status":"publish","type":"post","link":"https:\/\/calmaylagom.eu\/index.php\/2023\/08\/15\/visita-a-becerril-de-campos\/","title":{"rendered":"Visita a Becerril de Campos"},"content":{"rendered":"\n<p>En el mes de julio estuvimos de vacaciones en Espa\u00f1a y aprovechamos para visitar algunos lugares que se alejan de las rutas t\u00edpicas de los turistas. Uno de esos lugares es la localidad de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Becerril_de_Campos\">Becerril de Campos<\/a> en la provincia de Palencia. <\/p>\n\n\n\n<p>Becerril esconde una joya en sus calles: una antigua iglesia convertida en un templo de la astronom\u00eda y de la f\u00edsica. Es el <a href=\"https:\/\/becerrildecampos.es\/que-ver\/san-pedro-cultural\/\">edificio<\/a> de San Pedro Cultural.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">De Iglesia a centro de ciencia<\/h2>\n\n\n\n<p>La visita al centro San Pedro Cultural es entrar en un lugar dedicado por completo a la Ciencia y en particular a la F\u00edsica y a la Astronom\u00eda. <\/p>\n\n\n\n<p>El edificio es una antigua iglesia rom\u00e1nica del S. XII. En el siglo pasado, la iglesia estaba en ruinas y a un grupo de personas se les ocurri\u00f3 la genial idea de usar el edificio para construir un centro dedicado a la Astronom\u00eda. <\/p>\n\n\n\n<p>Dentro podemos encontrar desde un <a href=\"https:\/\/es.wikipedia.org\/wiki\/P%C3%A9ndulo_de_Foucault\">p\u00e9ndulo de Foucault<\/a> hasta un mural donde se representan las ecuaciones tensoriales de la relatividad general de Albert Einstein. De igual modo se encuentra la \u00fanica l\u00ednea meridiano en funcionamiento en Espa\u00f1a que nos muestran un calendario astron\u00f3mico a lo largo del a\u00f1o. La fachada De la Iglesia tiene un reloj solar. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfRelatividad general en Tierra de Campos?<\/h2>\n\n\n\n<p>Si, como suena, las ecuaciones tensoriales de Einstein de la Relatividad general est\u00e1n representadas como indicaba antes en un mural del edificio. <\/p>\n\n\n\n<p>Estas ecuaciones son una de las maravillas de la F\u00edsica y a mi parecer representan uno de los hitos m\u00e1s importantes alcanzados hasta la fecha. Agujeros negros, ondas gravitacionales, y mucho m\u00e1s se pueden deducir de las ecuaciones. <\/p>\n\n\n\n<p>Por cierto, el GPS que usa el m\u00f3vil que tienes en tus manos cuando lees esta entrada emplea relatividad para funcionar. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ideas para la visita<\/h2>\n\n\n\n<p>Nosotros comenzamos la visita en la plaza del pueblo tomando una tapa en el bar y de all\u00ed nos dirigimos al centro cultural. La gu\u00eda del centro explica todo perfectamente y se encuentra adem\u00e1s una exposici\u00f3n con objetos cient\u00edficos y p\u00f3steres de la NASA. <\/p>\n\n\n\n<p>Del centro cultural merece la pena un paseo por el pueblo y a lo largo del canal de Castilla donde se pueden disfrutar estampas preciosas como la de la fotograf\u00eda. <\/p>\n\n\n\n<p>Y de Becerril os recomiendo dirigiros al Mirador de Tierra de Campos y de all\u00ed a Fr\u00f3mista<\/p>\n\n\n<div id=\"metaslider-id-495\" style=\"width: 100%;\" class=\"ml-slider-3-104-0 metaslider metaslider-flex metaslider-495 ml-slider has-dots-nav ms-theme-blend\" role=\"region\" aria-label=\"New Slideshow\" data-height=\"463\" data-width=\"1064\">\n    <div id=\"metaslider_container_495\">\n        <div id=\"metaslider_495\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-502 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-08-15 18:40:10\" data-filename=\"Becerril_001-1024x445.jpg\" data-slide-type=\"image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/08\/Becerril_001.jpg?resize=740%2C322&#038;ssl=1\" height=\"322\" width=\"740\" alt=\"\" class=\"slider-495 slide-502 msDefaultImage\" title=\"Becerril_001\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-503 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-08-15 18:40:10\" data-filename=\"Becerril_014-1024x445.jpg\" data-slide-type=\"image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/08\/Becerril_014.jpg?resize=740%2C322&#038;ssl=1\" height=\"322\" width=\"740\" alt=\"\" class=\"slider-495 slide-503 msDefaultImage\" title=\"Becerril_014\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-504 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-08-15 18:40:10\" data-filename=\"Becerril_016-1024x445.jpg\" data-slide-type=\"image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/08\/Becerril_016.jpg?resize=740%2C322&#038;ssl=1\" height=\"322\" width=\"740\" alt=\"\" class=\"slider-495 slide-504 msDefaultImage\" title=\"Becerril_016\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-505 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-08-15 18:40:10\" data-filename=\"Becerril_017-1024x445.jpg\" data-slide-type=\"image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/08\/Becerril_017.jpg?resize=740%2C322&#038;ssl=1\" height=\"322\" width=\"740\" alt=\"\" class=\"slider-495 slide-505 msDefaultImage\" title=\"Becerril_017\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-506 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-08-15 18:40:10\" data-filename=\"Becerril_025-scaled-1064x463.jpg\" data-slide-type=\"image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/08\/Becerril_025-scaled.jpg?resize=740%2C322&#038;ssl=1\" height=\"322\" width=\"740\" alt=\"\" class=\"slider-495 slide-506 msDefaultImage\" title=\"Becerril_025\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Fr\u00f3mista<\/h2>\n\n\n\n<p>Si el arte rom\u00e1nico tiene un punto de referencia es sin duda la Iglesia de San Mart\u00edn de Fr\u00f3mista. <\/p>\n\n\n\n<p>Es un monumento precioso t\u00edpicamente rom\u00e1nico. En su interior, se puede encontrar informaci\u00f3n sobre historias de la nobleza de la \u00e9poca en que fue construido. Leyendo detenidamente se encuentran cosas muy interesantes<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"518\" src=\"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/08\/Becerril_032-1.jpg?resize=740%2C518&#038;ssl=1\" alt=\"\" class=\"wp-image-507\" srcset=\"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/08\/Becerril_032-1.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/08\/Becerril_032-1.jpg?resize=300%2C210&amp;ssl=1 300w, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/08\/Becerril_032-1.jpg?resize=768%2C538&amp;ssl=1 768w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><figcaption class=\"wp-element-caption\">Iglesia de San Mart\u00edn de Fr\u00f3mista, ejemplo de arte rom\u00e1nico.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Recuerda siempre \u2026 <\/h2>\n\n\n\n<p>No es necesario viajar a rutas ex\u00f3ticas y lejanas. En la mayor\u00eda de las ocasiones al ladito de casa se encuentran peque\u00f1as maravillas como este viaje a la localidad de Becerril. Es un pueblecito de la provincia de Palencia con menos de 1000 habitantes pero que merece mucho la pena. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el mes de julio estuvimos de vacaciones en Espa\u00f1a y aprovechamos para visitar algunos lugares que se alejan de las rutas t\u00edpicas de los turistas. Uno de esos lugares es la localidad de Becerril de Campos en la provincia de Palencia. Becerril esconde una joya en sus calles: una antigua iglesia convertida en un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":492,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[5],"tags":[48,47],"class_list":["post-493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes","tag-espana","tag-palencia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/08\/Becerril_003-scaled-e1692122085114.jpg?fit=1024%2C819&ssl=1","jetpack-related-posts":[{"id":554,"url":"https:\/\/calmaylagom.eu\/index.php\/2024\/02\/02\/valladolid-ciudad-de-cultura-y-mi-ciudad-pucela\/","url_meta":{"origin":493,"position":0},"title":"Valladolid, ciudad de cultura y mi ciudad. Pucela.","author":"admin","date":"2024-02-02","format":false,"excerpt":"Valladolid, ciudad de Zorrilla, los Celtas, el Pucela y mucho mas.","rel":"","context":"In &quot;Travel&quot;","block_context":{"text":"Travel","link":"https:\/\/calmaylagom.eu\/index.php\/category\/travel\/"},"img":{"alt_text":"Valladolid Zorrilla","src":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2024\/02\/20231231_casaZorrilla09-scaled.jpg?fit=730%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2024\/02\/20231231_casaZorrilla09-scaled.jpg?fit=730%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2024\/02\/20231231_casaZorrilla09-scaled.jpg?fit=730%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2024\/02\/20231231_casaZorrilla09-scaled.jpg?fit=730%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":152,"url":"https:\/\/calmaylagom.eu\/index.php\/2021\/11\/13\/ese-verano-especial\/","url_meta":{"origin":493,"position":1},"title":"Ese verano especial","author":"admin","date":"2021-11-13","format":false,"excerpt":"En muchas ocasiones ocurre que planeas algo, lo organizas durante mucho tiempo y, de repente, en un segundo, todo cambia. Eso me ocurri\u00f3 a mi en el verano de 2021.\u00a0 Al final, por motivos personales, tuvimos que viajar a mi querida Valladolid y all\u00ed pasamos el mes de julio de\u2026","rel":"","context":"In &quot;Viajes&quot;","block_context":{"text":"Viajes","link":"https:\/\/calmaylagom.eu\/index.php\/category\/viajes\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2021\/10\/IMG_8853-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2021\/10\/IMG_8853-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2021\/10\/IMG_8853-scaled.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2021\/10\/IMG_8853-scaled.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2021\/10\/IMG_8853-scaled.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":467,"url":"https:\/\/calmaylagom.eu\/index.php\/2023\/02\/05\/ahora-que-llega-el-cometa\/","url_meta":{"origin":493,"position":2},"title":"Ahora que llega el cometa &#8230;","author":"admin","date":"2023-02-05","format":false,"excerpt":"En este mes de enero y principios de febrero se ha aproximado a nuestro querido planeta Tierra el cometa C\/2022 E3 (ZTF) que desde hace 50000 a\u00f1os no se ve\u00eda. Bueno, en realidad no lo ha visto nadie porque la \u00faltima vez que paso no exist\u00eda nada de lo que\u2026","rel":"","context":"In &quot;Ciencia&quot;","block_context":{"text":"Ciencia","link":"https:\/\/calmaylagom.eu\/index.php\/category\/ciencia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/02\/The_Blue_Marble_remastered-3.jpg?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/02\/The_Blue_Marble_remastered-3.jpg?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/02\/The_Blue_Marble_remastered-3.jpg?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/02\/The_Blue_Marble_remastered-3.jpg?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2023\/02\/The_Blue_Marble_remastered-3.jpg?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1,"url":"https:\/\/calmaylagom.eu\/index.php\/2021\/08\/08\/hello-world\/","url_meta":{"origin":493,"position":3},"title":"Bienvenido a tu espacio de calma y lagom","author":"admin","date":"2021-08-08","format":false,"excerpt":"Despu\u00e9s de muchos a\u00f1os por fin he podido hacer realidad este proyecto: una p\u00e1gina web propia.\u00a0 Te doy la bienvenida a mi p\u00e1gina web. Es un espacio en el que la idea es esencialmente emitir toda la energ\u00eda positiva que sea posible. \u00bfY c\u00f3mo se puede hacer esto? Hay muchas\u2026","rel":"","context":"In &quot;Sobre el autor&quot;","block_context":{"text":"Sobre el autor","link":"https:\/\/calmaylagom.eu\/index.php\/category\/sobre-el-autor\/"},"img":{"alt_text":"valladolid uppsala","src":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2021\/08\/IMG_6215-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2021\/08\/IMG_6215-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2021\/08\/IMG_6215-scaled.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2021\/08\/IMG_6215-scaled.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2021\/08\/IMG_6215-scaled.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":751,"url":"https:\/\/calmaylagom.eu\/index.php\/2025\/08\/21\/week-202534-newsletter-ciencia-y-otras-cositas-arde-la-peninsula\/","url_meta":{"origin":493,"position":4},"title":"Arde la pen\u00ednsula","author":"admin","date":"2025-08-21","format":false,"excerpt":"Esta edici\u00f3n de la newsletter en agosto de 2025 se escribe mientras arden miles de hect\u00e1reas en much\u00edsimos lugares de Europa, en particular en la pen\u00ednsula Ib\u00e9rica y m\u00e1s en concreto en mi regi\u00f3n, en Castilla y Le\u00f3n. Pero la edici\u00f3n no va a hablar de las conexiones entre cambio\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2025\/08\/portada-scaled.jpeg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2025\/08\/portada-scaled.jpeg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2025\/08\/portada-scaled.jpeg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2025\/08\/portada-scaled.jpeg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":569,"url":"https:\/\/calmaylagom.eu\/index.php\/2024\/02\/19\/newsletter-ciencia-y-otras-cositas-20240219\/","url_meta":{"origin":493,"position":5},"title":"Newsletter Ciencia y otras cositas &#8211; febrero 2024","author":"admin","date":"2024-02-19","format":false,"excerpt":"Estamos en el mes de febrero de 2024 y esta newsletter comienza a ser m\u00e1s regular. Lo primero de todo es agradecer a todos los subscriptores que en las diversas plataformas han decidido seguir esta publicaci\u00f3n. Estoy impresionado por el n\u00famero, no me esperaba tanto inter\u00e9s si soy sincero. Mil\u2026","rel":"","context":"In &quot;Ciencia&quot;","block_context":{"text":"Ciencia","link":"https:\/\/calmaylagom.eu\/index.php\/category\/ciencia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2024\/02\/20240217_salstaslott_35-1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2024\/02\/20240217_salstaslott_35-1.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2024\/02\/20240217_salstaslott_35-1.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/calmaylagom.eu\/wp-content\/uploads\/2024\/02\/20240217_salstaslott_35-1.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/calmaylagom.eu\/index.php\/wp-json\/wp\/v2\/posts\/493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calmaylagom.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/calmaylagom.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/calmaylagom.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/calmaylagom.eu\/index.php\/wp-json\/wp\/v2\/comments?post=493"}],"version-history":[{"count":4,"href":"https:\/\/calmaylagom.eu\/index.php\/wp-json\/wp\/v2\/posts\/493\/revisions"}],"predecessor-version":[{"id":510,"href":"https:\/\/calmaylagom.eu\/index.php\/wp-json\/wp\/v2\/posts\/493\/revisions\/510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/calmaylagom.eu\/index.php\/wp-json\/wp\/v2\/media\/492"}],"wp:attachment":[{"href":"https:\/\/calmaylagom.eu\/index.php\/wp-json\/wp\/v2\/media?parent=493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/calmaylagom.eu\/index.php\/wp-json\/wp\/v2\/categories?post=493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/calmaylagom.eu\/index.php\/wp-json\/wp\/v2\/tags?post=493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}